{"id":589,"count":217,"description":"<span style=\"font-weight: 400;\">Todas las empresas actuales saben que aparecer en Internet no es una opci\u00f3n sino una obligaci\u00f3n para garantizar la supervivencia dentro del mercado, cada d\u00eda m\u00e1s grande y competitivo. Internet es el escaparate m\u00e1s grande del mundo, por lo que ser\u00eda una locura no apostar por anunciarse dentro de \u00e9l.<\/span>\r\n\r\n<span style=\"font-weight: 400;\">Una forma de diferenciarse para las empresas es la capacidad que tienen de adaptarse a las nuevas tecnolog\u00edas y conseguir la atenci\u00f3n de los <\/span><b>nuevos consumidores digitales <\/b><span style=\"font-weight: 400;\">que buscan, comparan y opinan acerca de los productos y servicios que adquieren a trav\u00e9s de Internet. Por este motivo, es importante contar con formaci\u00f3n especializada en<\/span><b> Digital Business<\/b><span style=\"font-weight: 400;\"> que garantiza que el profesional sea capaz dirigir esta estrategia digital de la empresa.<\/span>","link":"https:\/\/www.iebschool.com\/hub\/business-tech\/digital-business\/","name":"Digital Business","slug":"digital-business","taxonomy":"category","parent":4,"meta":[],"_links":{"self":[{"href":"https:\/\/www.iebschool.com\/hub\/wp-json\/wp\/v2\/categories\/589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iebschool.com\/hub\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.iebschool.com\/hub\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.iebschool.com\/hub\/wp-json\/wp\/v2\/categories\/4"}],"wp:post_type":[{"href":"https:\/\/www.iebschool.com\/hub\/wp-json\/wp\/v2\/posts?categories=589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}